{"id":2038,"date":"2023-07-03T19:35:00","date_gmt":"2023-07-03T17:35:00","guid":{"rendered":"https:\/\/leportaildelumiere.com\/?p=2038"},"modified":"2024-11-06T13:47:31","modified_gmt":"2024-11-06T12:47:31","slug":"les-six-vertus-de-coeur","status":"publish","type":"post","link":"https:\/\/leportaildelumiere.com\/index.php\/2023\/07\/03\/les-six-vertus-de-coeur\/","title":{"rendered":"Les six vertus de coeur"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus.jpg?w=640&#038;ssl=1\" alt=\"\" class=\"wp-image-2039\" style=\"width:499px;height:auto\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Les six vertus de coeur sont devenues un th\u00e8me majeur des mat\u00e9riaux Lyricus et WingMakers et fournir une base solide pour aider les gens \u00e0 devenir des praticiens, et non pas seulement philosophiques enqu\u00eateurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans l&rsquo;interview Avril 2013, James a exprim\u00e9 ainsi:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u00ab Vous voyez, la r\u00e9citation de la philosophie est bas\u00e9e sur des mots et de l&rsquo;id\u00e9ologie mentale. Oui il peut changer les comportements pour \u00eatre s\u00fbr, mais il ne met pas les fr\u00e9quences ultra-fines dans l&rsquo;\u00eatre humain instrument, comportements seulement conformes aux vertus du coeur se purifier et pr\u00e9parer l&rsquo;instrument humain \u00e0 percevoir l&rsquo;\u00e2me ou soi sup\u00e9rieur. Pour voir ses mouvements, ses perspectives, ses id\u00e9es, sa conscience, les comportements. Donc, mettre sur la pr\u00e9paration de l\u2019instrument humain, et ces comportements doit \u00eatre coh\u00e9rente et claire, et la seule fa\u00e7on peut \u00eatre de cette qualit\u00e9, est de savoir si elles sont authentiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Vous ne pouvez pas truquer cela. Vous ne pouvez pas pratiquer comme une machine. Vous devez \u00eatre humain, vuln\u00e9rable, ouvert, humble et pr\u00eat \u00e0 apprendre de vous plus que vous \u00eates pr\u00eat \u00e0 accepter les mots d&rsquo;un autre.\u00a0\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>L\u2019appr\u00e9ciation ou la gratitude, la compassion, l\u2019humilit\u00e9, le pardon, la compr\u00e9hension, la bravoure et le courage. C\u2019est la combinaison du maintenant \u2013 de l\u2019\u00eatre dans le maintenant \u2013 et l\u2019application de ces mots dans nos comportements. C\u2019est \u00eatre impeccable dans cette pratique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>L\u2019amour n\u2019est pas fr\u00e9quemment utilis\u00e9 dans les mat\u00e9riaux WingMakers en g\u00e9n\u00e9ral. Je pense notamment que c\u2019est parce que le mot porte tellement de \u2018valises\u2019 dans ce monde. Il a une sorte d\u2019\u00e9nergie sentimentale, de co-d\u00e9pendance en termes de relations, et puis dans la culture il est utilis\u00e9 avec tant de d\u00e9sinvolture, presque comme un slogan, tout ce que les gens utilisent pour saluer quelqu\u2019un comme: \u00ab Comment allez-vous? \u00bb. L\u2019amour est la force unificatrice. Ce n\u2019est que cela, et encore, \u00e0 bien des \u00e9gards, c\u2019est tout. Du point de vue des WingMakers, c\u2019est un mot-concept tr\u00e8s important, m\u00eame s\u2019ils l\u2019utilisent avec parcimonie. Les six vertus de coeur que j\u2019ai mentionn\u00e9es sont consid\u00e9r\u00e9es comme les diff\u00e9rentes fa\u00e7ons dont l\u2019amour se manifeste dans nos comportements. Dans cette mesure, l\u2019amour s\u2019exprime dans les comportements vertueux tels la gratitude, la compassion, le pardon et l\u2019humilit\u00e9. Dans ce contexte, les six vertus de coeur, collectivement, sont l\u2019expression de l\u2019amour dans la dimension humaine. \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les six vertus de coeur sont devenues un th\u00e8me majeur des mat\u00e9riaux Lyricus et WingMakers&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2039,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"cybocfi_hide_featured_image":"yes","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[33],"tags":[],"class_list":["post-2038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-complement"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?fit=573%2C581&ssl=1","featured_image_urls":{"full":["https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?fit=573%2C581&ssl=1",573,581,false],"thumbnail":["https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?fit=296%2C300&ssl=1",296,300,true],"medium_large":["https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?fit=573%2C581&ssl=1",573,581,true],"large":["https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?fit=573%2C581&ssl=1",573,581,true],"1536x1536":["https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?fit=573%2C581&ssl=1",573,581,true],"2048x2048":["https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?fit=573%2C581&ssl=1",573,581,true],"covernews-featured":["https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?fit=573%2C581&ssl=1",573,581,true],"covernews-medium":["https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?resize=540%2C340&ssl=1",540,340,true],"woocommerce_thumbnail":["https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?resize=300%2C300&ssl=1",300,300,true],"woocommerce_single":["https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?fit=573%2C581&ssl=1",573,581,true],"woocommerce_gallery_thumbnail":["https:\/\/i0.wp.com\/leportaildelumiere.com\/wp-content\/uploads\/2024\/11\/vertus-e1730897156375.jpg?resize=100%2C100&ssl=1",100,100,true]},"author_info":{"display_name":"Pierre","author_link":"https:\/\/leportaildelumiere.com\/index.php\/author\/pierre-ortiz\/"},"category_info":"<a href=\"https:\/\/leportaildelumiere.com\/index.php\/category\/complement\/\" rel=\"category tag\">Compl\u00e9ment<\/a>","tag_info":"Compl\u00e9ment","comment_count":"1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/leportaildelumiere.com\/index.php\/wp-json\/wp\/v2\/posts\/2038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leportaildelumiere.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leportaildelumiere.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leportaildelumiere.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leportaildelumiere.com\/index.php\/wp-json\/wp\/v2\/comments?post=2038"}],"version-history":[{"count":0,"href":"https:\/\/leportaildelumiere.com\/index.php\/wp-json\/wp\/v2\/posts\/2038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leportaildelumiere.com\/index.php\/wp-json\/wp\/v2\/media\/2039"}],"wp:attachment":[{"href":"https:\/\/leportaildelumiere.com\/index.php\/wp-json\/wp\/v2\/media?parent=2038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leportaildelumiere.com\/index.php\/wp-json\/wp\/v2\/categories?post=2038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leportaildelumiere.com\/index.php\/wp-json\/wp\/v2\/tags?post=2038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}